{"id":137131,"date":"2026-05-06T11:36:40","date_gmt":"2026-05-06T11:36:40","guid":{"rendered":"https:\/\/docs.daftra.com\/tutorial\/%d8%aa%d9%81%d8%b9%d9%8a%d9%84-%d8%aa%d8%b7%d8%a8%d9%8a%d9%82-%d8%a7%d9%84%d9%81%d8%a7%d8%aa%d9%88%d8%b1%d8%a9-%d8%a7%d9%84%d8%a5%d9%84%d9%83%d8%aa%d8%b1%d9%88%d9%86%d9%8a%d8%a9-%d8%a7%d9%84%d8%a5\/"},"modified":"2026-05-13T09:16:11","modified_gmt":"2026-05-13T09:16:11","slug":"enabling-the-uae-e-invoice-application","status":"publish","type":"tutorial","link":"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/","title":{"rendered":"Enabling the UAE E-Invoice Application"},"content":{"rendered":"","protected":false},"author":17,"featured_media":0,"template":"","categories":[2036,9686],"tags":[],"class_list":["post-137131","tutorial","type-tutorial","status-publish","hentry","category-sales","category-e-invoicing-uae"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Enabling the UAE E-Invoice Application - Daftra Knowledge Base<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enabling the UAE E-Invoice Application - Daftra Knowledge Base\" \/>\n<meta property=\"og:url\" content=\"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/\" \/>\n<meta property=\"og:site_name\" content=\"Daftra Knowledge Base\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T09:16:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/docs.daftra.com\/#website\",\"url\":\"https:\/\/docs.daftra.com\/\",\"name\":\"Daftra Knowledge Base\",\"description\":\"Daftra\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/docs.daftra.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/#webpage\",\"url\":\"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/\",\"name\":\"Enabling the UAE E-Invoice Application - Daftra Knowledge Base\",\"isPartOf\":{\"@id\":\"https:\/\/docs.daftra.com\/#website\"},\"datePublished\":\"2026-05-06T11:36:40+00:00\",\"dateModified\":\"2026-05-13T09:16:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/docs.daftra.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enabling the UAE E-Invoice Application\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enabling the UAE E-Invoice Application - Daftra Knowledge Base","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/","og_locale":"en_US","og_type":"article","og_title":"Enabling the UAE E-Invoice Application - Daftra Knowledge Base","og_url":"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/","og_site_name":"Daftra Knowledge Base","article_modified_time":"2026-05-13T09:16:11+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/docs.daftra.com\/#website","url":"https:\/\/docs.daftra.com\/","name":"Daftra Knowledge Base","description":"Daftra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/docs.daftra.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/#webpage","url":"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/","name":"Enabling the UAE E-Invoice Application - Daftra Knowledge Base","isPartOf":{"@id":"https:\/\/docs.daftra.com\/#website"},"datePublished":"2026-05-06T11:36:40+00:00","dateModified":"2026-05-13T09:16:11+00:00","breadcrumb":{"@id":"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/docs.daftra.com\/en\/tutorial\/enabling-the-uae-e-invoice-application\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/docs.daftra.com\/en\/"},{"@type":"ListItem","position":2,"name":"Enabling the UAE E-Invoice Application"}]}]}},"_links":{"self":[{"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/tutorial\/137131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/tutorial"}],"about":[{"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/types\/tutorial"}],"author":[{"embeddable":true,"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":2,"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/tutorial\/137131\/revisions"}],"predecessor-version":[{"id":137133,"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/tutorial\/137131\/revisions\/137133"}],"wp:attachment":[{"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/media?parent=137131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/categories?post=137131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/tags?post=137131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}