{"id":9994,"count":1,"description":"","link":"https:\/\/docs.daftra.com\/en\/category\/%d8%a7%d9%84%d8%aa%d9%82%d8%a7%d8%b1%d9%8a%d8%b1-en\/","name":"\u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631","slug":"%d8%a7%d9%84%d8%aa%d9%82%d8%a7%d8%b1%d9%8a%d8%b1-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631 - Daftra Knowledge Base<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/docs.daftra.com\/en\/category\/\u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631 - Daftra Knowledge Base\" \/>\n<meta property=\"og:url\" content=\"https:\/\/docs.daftra.com\/en\/category\/\u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Daftra Knowledge Base\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/docs.daftra.com\/#website\",\"url\":\"https:\/\/docs.daftra.com\/\",\"name\":\"Daftra Knowledge Base\",\"description\":\"Daftra\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/docs.daftra.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/docs.daftra.com\/en\/category\/%d8%a7%d9%84%d8%aa%d9%82%d8%a7%d8%b1%d9%8a%d8%b1-en\/#webpage\",\"url\":\"https:\/\/docs.daftra.com\/en\/category\/%d8%a7%d9%84%d8%aa%d9%82%d8%a7%d8%b1%d9%8a%d8%b1-en\/\",\"name\":\"\\u0627\\u0644\\u062a\\u0642\\u0627\\u0631\\u064a\\u0631 - Daftra Knowledge Base\",\"isPartOf\":{\"@id\":\"https:\/\/docs.daftra.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/docs.daftra.com\/en\/category\/%d8%a7%d9%84%d8%aa%d9%82%d8%a7%d8%b1%d9%8a%d8%b1-en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/docs.daftra.com\/en\/category\/%d8%a7%d9%84%d8%aa%d9%82%d8%a7%d8%b1%d9%8a%d8%b1-en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/docs.daftra.com\/en\/category\/%d8%a7%d9%84%d8%aa%d9%82%d8%a7%d8%b1%d9%8a%d8%b1-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/docs.daftra.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u0627\\u0644\\u062a\\u0642\\u0627\\u0631\\u064a\\u0631\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631 - Daftra Knowledge Base","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/docs.daftra.com\/en\/category\/\u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631-en\/","og_locale":"en_US","og_type":"article","og_title":"\u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631 - Daftra Knowledge Base","og_url":"https:\/\/docs.daftra.com\/en\/category\/\u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631-en\/","og_site_name":"Daftra Knowledge Base","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/docs.daftra.com\/#website","url":"https:\/\/docs.daftra.com\/","name":"Daftra Knowledge Base","description":"Daftra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/docs.daftra.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"CollectionPage","@id":"https:\/\/docs.daftra.com\/en\/category\/%d8%a7%d9%84%d8%aa%d9%82%d8%a7%d8%b1%d9%8a%d8%b1-en\/#webpage","url":"https:\/\/docs.daftra.com\/en\/category\/%d8%a7%d9%84%d8%aa%d9%82%d8%a7%d8%b1%d9%8a%d8%b1-en\/","name":"\u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631 - Daftra Knowledge Base","isPartOf":{"@id":"https:\/\/docs.daftra.com\/#website"},"breadcrumb":{"@id":"https:\/\/docs.daftra.com\/en\/category\/%d8%a7%d9%84%d8%aa%d9%82%d8%a7%d8%b1%d9%8a%d8%b1-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/docs.daftra.com\/en\/category\/%d8%a7%d9%84%d8%aa%d9%82%d8%a7%d8%b1%d9%8a%d8%b1-en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/docs.daftra.com\/en\/category\/%d8%a7%d9%84%d8%aa%d9%82%d8%a7%d8%b1%d9%8a%d8%b1-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/docs.daftra.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631"}]}]}},"_links":{"self":[{"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/categories\/9994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/posts?categories=9994"},{"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/tutorial?categories=9994"},{"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/user_manual?categories=9994"},{"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/video?categories=9994"},{"href":"https:\/\/docs.daftra.com\/en\/wp-json\/wp\/v2\/faq?categories=9994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}